{"id":12508,"date":"2022-11-20T08:20:53","date_gmt":"2022-11-20T12:20:53","guid":{"rendered":"https:\/\/energiesnet.com\/espanol\/?p=12508"},"modified":"2022-11-20T11:17:01","modified_gmt":"2022-11-20T15:17:01","slug":"liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas","status":"publish","type":"post","link":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/","title":{"rendered":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/11\/maduro_petro_ortegaa_diaz-canel-gcoronel.jpg\" alt=\"\" class=\"wp-image-12509\" width=\"1195\" height=\"697\" srcset=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/11\/maduro_petro_ortegaa_diaz-canel-gcoronel.jpg 600w, https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/11\/maduro_petro_ortegaa_diaz-canel-gcoronel-300x175.jpg 300w\" sizes=\"(max-width: 1195px) 100vw, 1195px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por Gustavo Coronel  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos&nbsp;sedientos del poder, los hay payasos, y hasta uno que otro estadista.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La lista de requerimientos para conducir un pa\u00eds en nuestro hemisferio ha cambiado de manera dram\u00e1tica. Hubo una \u00e9poca, durante el siglo XX, que la condici\u00f3n de l\u00edder exig\u00eda honestidad, sensatez, valor c\u00edvico y, como condici\u00f3n indispensable, una amplia conciencia ciudadana, m\u00e1s&nbsp;all\u00e1 de ego\u00edstas intereses tribales&nbsp;o&nbsp;&nbsp;partidistas&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s no todos los l\u00edderes pose\u00edan todas esas cualidades, pero, en general, era dif\u00edcil&nbsp;llegar al tope de la pir\u00e1mide pol\u00edtica en cada pa\u00eds sin exhibir un claro perfil ciudadano. Recordemos a Franklin D. Roosevelt, a Harry Truman y a Ronald Reagan en USA, a Alberto Lleras Camargo, Alfonso L\u00f3pez y Eduardo Santos en Colombia; a R\u00f3mulo Gallegos, Isa\u00edas Medina Angarita, R\u00f3mulo Betancourt y Rafael Caldera (I) en Venezuela; a Fernando Enrique Cardoso en Brasil; a Ra\u00fal Alfons\u00edn y Arturo Ilia en Argentina; a Ricardo Lagos y Michel Bachelet en Chile; a Tabar\u00e9 V\u00e1squez y Luis Lacalle en Uruguay y, a Oscar Arias y Alberto Monge en Costa Rica. Hubo m\u00e1s\u2026&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfqu\u00e9 es lo que tenemos hoy? &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los \u00faltimos 6 a\u00f1os la presidencia de los Estados Unidos de Am\u00e9rica ha estado en manos, primero, de un fan\u00e1tico destructor de las instituciones y ansioso de poder como Donald&nbsp;Trump y, luego, de&nbsp;un l\u00edder d\u00e9bil y senil, como Joseph Biden. Como si esto no fuera suficiente, el pa\u00eds probablemente deber\u00e1 enfrentar una&nbsp;nueva elecci\u00f3n entre&nbsp;el uno y el otro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Brasil han tenido que elegir entre un ladr\u00f3n como Lula da Silva y un fan\u00e1tico, destructor de la Amazonia como Jair Bolsonaro. En Colombia el exguerrillero Gustavo Petro fue elegido, en preferencia a un extremista de derecha y de lenguaje cloacal. En Per\u00fa, un payaso como Pedro Castillo se mantiene hoy el poder a pesar de que nadie parece quererlo, mientras sus antecesores est\u00e1n en la c\u00e1rcel o son pr\u00f3fugos de la justicia por peculado.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En Venezuela y Nicaragua un par de forajidos impresentables, como Nicol\u00e1s Maduro y Daniel Ortega, imperan junto a sus torvas esposas sobre las ruinas de sus pa\u00edses.&nbsp;&nbsp;En Cuba los hermanos Castro han instalado un r\u00e9gimen de terror que ha castrado espiritualmente a esa naci\u00f3n. En Argentina, Bolivia, Honduras y El Salvador, mandan l\u00edderes mediocres, dedicados a proteger sus tribus ideol\u00f3gicas o a exaltar sus egos.&nbsp;&nbsp;En M\u00e9xico, un patriotero acomplejado como Andr\u00e9s L\u00f3pez Obrador genera atraso y resentimiento de clases. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo en los eternos bastiones de la democracia hemisf\u00e9rica, Costa Rica y Uruguay, existen presidencias de naturaleza democr\u00e1tica, donde las personas son menos poderosas que el sistema y est\u00e1n&nbsp;&nbsp;dedicadas a preservar la armon\u00eda social&nbsp;&nbsp;en sus pa\u00edses, aunque \u2013 debemos aceptar &#8211;&nbsp;&nbsp;el presidente de Costa Rica haya tenido que enfrentar acusaciones de acoso sexual mientras trabaj\u00f3 para el Banco Mundial.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este espeluznante deterioro de la calidad del liderazgo pol\u00edtico hemisf\u00e9rico no ha sido generado en&nbsp;el vac\u00edo. Ha sido un producto de la mediocrizaci\u00f3n de las sociedades durante las \u00faltimas d\u00e9cadas, un proceso que, una vez en marcha, retroalimenta la mediocrizaci\u00f3n. Estudios de la Corporaci\u00f3n RAND y extraordinarios an\u00e1lisis como los de Mois\u00e9s Na\u00edm en su libro \u201cLa Revancha de los poderosos\u201d, ver:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/www.rand.org\/research\/projects\/truth-decay\/about-truth-decay.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.rand.org\/research\/projects\/truth-decay\/about-truth-decay.html<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/lasarmasdecoronel.blogspot.com\/2022\/03\/el-nuevo-libro-de-moises-naim-sobre-las.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/lasarmasdecoronel.blogspot.com\/2022\/03\/el-nuevo-libro-de-moises-naim-sobre-las.html<\/a>, llaman la atenci\u00f3n sobre el fen\u00f3meno que explica mucha de este deterioro. Se trata de lo que RAND denomina&nbsp;<em>el Deterioro de la Verdad<\/em>&nbsp;y Na\u00edm define como&nbsp;<em>la Pos Verdad.&nbsp;<\/em>En esencia se trata de la p\u00e9rdida del valor de la verdad como br\u00fajula moral para la toma de decisiones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los seres humanos tienen por naturaleza diferentes perspectivas sobre los asuntos que les conciernen, comenzando por, quiz\u00e1s, el m\u00e1s \u00e1lgido, la&nbsp;existencia de Dios, el cual es de imposible verificaci\u00f3n. La mayor\u00eda de los asuntos tienen posibilidad de verificaci\u00f3n, por lo cual lo sensato ser\u00eda compartir estos datos a fin de lograr ponernos de acuerdo. Sin embargo, hoy se acent\u00faan las diferencias apasionadas sobre asuntos que pueden ser verificables. Hay miles de personas quienes&nbsp;creen que los humanos nunca viajaron a la Luna, que la Tierra es plana, y que Elvis Presley no muri\u00f3, sino que vive en Nueva Orleans de inc\u00f3gnito, ayudado por la cirug\u00eda pl\u00e1stica.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desconocimiento de la verdad objetiva ha&nbsp;&nbsp;pasado a ser el frecuente producto&nbsp;de un sesgo cognitivo, el cual parece&nbsp;tener dos vertientes, la de quien realmente es incapaz de ver la verdad por sus limitaciones mentales o por su ignorancia o de quien la ve, pero prefiere negarla debido a que colide con la chaqueta de fuerza ideol\u00f3gica que se lo impide. En los dos casos el efecto nocivo sobre la armon\u00eda social es similar, representa la p\u00e9rdida de la br\u00fajula que gu\u00eda a las sociedades en su mecanismo de toma de decisiones. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sesgo cognitivo no est\u00e1 limitado a una corriente particular de pensamiento, ocurre entre gentes que simplemente han creado sus propios universos ideol\u00f3gicos de la extrema izquierda o de la extrema derecha, esas versiones telegr\u00e1ficas con las cuales representamos nuestra incapacidad para ponernos de acuerdo.&nbsp;&nbsp;Hoy d\u00eda ese clivaje es profundo, son dos grupos que se alinean en campos frecuentemente dominados por el resentimiento o hasta por el odio. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo sensato es que las sociedades tomen decisiones basadas en un universo de datos objetivos que pueda ser compartido por todos. Yo salgo a la calle con abrigo si las mediciones meteorol\u00f3gicas me dicen que va a ser un d\u00eda fr\u00edo, en necesidad de protecci\u00f3n. Pero, si alguien comienza a decir que esa predicci\u00f3n no es cierta porque est\u00e1 pagada&nbsp;<em>por un vendedor de abrigos, de guantes o de gorros<\/em>, se abre de inmediato una brecha de credibilidad que lleva a mucha gente a salir sin protecci\u00f3n, con la posibilidad de neumon\u00edas y muertes que no deber\u00edan haber ocurrido. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La negaci\u00f3n o distorsi\u00f3n de la verdad objetiva est\u00e1 llevando a muchas sociedades del planeta, incluyendo las m\u00e1s pr\u00f3speras, a un dram\u00e1tico deterioro. Entre los ejemplos m\u00e1s dram\u00e1ticos de este profundo desencuentro puedo mencionar tres: La elecci\u00f3n presidencial que llev\u00f3 la presidencia a Joseph Biden en USA; la controversia sobre la vacuna contra el COVID y la pugna sobre la existencia o no del cambio clim\u00e1tico. Aunque sobre estos tres asuntos globales hay copiosos datos, el mundo est\u00e1 envuelto en una batalla tr\u00e1gica entre quienes apoyan y quienes niegan. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La elecci\u00f3n que llev\u00f3 a Joseph Biden a la presidencia de los Estados Unidos ha podido ser manejada por el presidente derrotado como siempre lo hab\u00edan hecho todos sus antecesores, es decir, la gr\u00e1cil aceptaci\u00f3n de la derrota, actitud que es parte integral del alma estadounidense. En este caso, ello no se dio porque Trump aleg\u00f3 y aun alega que su victoria&nbsp;le fue escamoteada por un sistema corrupto, aunque todas las instancias judiciales, legislativas y ejecutivas de la naci\u00f3n hayan corroborado la victoria de Biden como leg\u00edtima. La insistencia de Trump en un fraude ha servido para erosionar la credibilidad de las&nbsp;instituciones del pa\u00eds, para sembrar el odio y el resentimiento entre la poblaci\u00f3n y hasta para su enriquecimiento personal, ya que ha recibido millones de d\u00f3lares de sus partidarios para \u201cluchar contra el fraude\u201d. Como resultado, los Estados Unidos de hoy son una naci\u00f3n peligrosamente fragmentada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vacunaci\u00f3n contra el COVID, la cual ha salvado millones de vidas en todo el mundo ha encontrado importantes bolsillos de resistencia animados por las m\u00e1s variadas objeciones de tipo pseudocient\u00edfico, pol\u00edtico&nbsp;y hasta religioso. No sabemos cu\u00e1ntas muertes se deben a este desconocimiento sin basamento cient\u00edfico. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pugna sobre el cambio clim\u00e1tico es compleja y ha&nbsp;adquirido una fisonom\u00eda casi religiosa, pues hay quienes niegan que mucho del deterioro clim\u00e1tico se deba a la acci\u00f3n del hombre. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que nos pasa es que est\u00e1 desapareciendo el centro. Vivimos en blanco y negro, en azul o rojo y esta polarizaci\u00f3n irracional imposibilita encontrar las soluciones que realmente sirvan al bienestar del planeta. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfHay soluci\u00f3n a esta tragedia? Ninguna parece ser ya de corto plazo. La corporaci\u00f3n RAND menciona cuatro posibles v\u00edas: (1), la educaci\u00f3n c\u00edvica y en valores; (2), sembrar confianza en las instituciones mediante una mayor transparencia en sus acciones: (3), Cambiar la manera la informaci\u00f3n es transmitida, a fin de separar m\u00e1s claramente los hechos de la opini\u00f3n y, (4), combatir vigorosamente la desinformaci\u00f3n que prevalece hoy. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como se podr\u00e1 observar, ninguno de estos cuatro pasos surtir\u00e1 efectos de corto plazo y, para tener \u00e9xito, todos deber\u00e1n ser aplicados con perseverancia. Lo que se nos pide es un cambio actitudinal importante, el cual tomar\u00e1 tanto tiempo como ha tomado el llegar a la deplorable situaci\u00f3n de hoy. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La batalla es tit\u00e1nica, pero tiene que darse porque las consecuencias de perderla es la anom\u00eda global. Si no es posible lograr verlo de esta manera, este planeta no va pal baile. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">_______________________________________________<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Gustavo Coronel<\/em><\/strong>, Ge\u00f3logo y Polit\u00f3logo venezolano, post \u2013 grado y estudios en la Universidad de Tulsa (1951-1955), Universidad Central de Venezuela (1961), Harvard (1981-1982) y Johns Hopkins&nbsp;&nbsp;(1986-1987). Trabaj\u00f3 durante 27 a\u00f1os en la industria petrolera venezolana e internacional. Miembro fundador de la Directiva de Petr\u00f3leos de Venezuela (1976-1979). Desde 1983 en adelante se dedic\u00f3 a trabajar en el sector p\u00fablico desde el Banco Interamericano de Desarrollo (1983-1988), como Director general de la CVG (1994-1995), Secretario de Planificaci\u00f3n y Presupuesto del estado Carabobo (1996-1998) y Presidente del Puerto de Puerto Cabello (1999-2001). Por varios meses en 1999 fue diputado al Congreso Nacional por el estado Carabobo. En 2003 se exili\u00f3 voluntariamente y reside desde entonces en el estado de Virginia, USA, donde ha encontrado tranquilidad y felicidad. Los puntos de vista expresados no necesariamente son los de EnergiesNet.com.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nota del Editor:&nbsp;Este art\u00edculo fue originalmente publicado en&nbsp;<em><a href=\"http:\/\/lasarmasdecoronel.blogspot.com\/\">Las Armas de Coronel,&nbsp;<\/a><\/em>el  3 de noviembre laboradores y columnistas de opini\u00f3n y an\u00e1lisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/lasarmasdecoronel.blogspot.com\/2022\/11\/liderazgo-politico-hemisferico-seniles.html\">Articulo original<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aviso de uso: Este sitio contiene material protegido por derechos de autor cuyo uso no siempre ha sido espec\u00edficamente autorizado por el propietario de los derechos. Ponemos a disposici\u00f3n dicho material en nuestro esfuerzo por avanzar en la comprensi\u00f3n de cuestiones de importancia social, medioambiental y humanitaria. Creemos que esto constituye un \u00abuso justo\u00bb de dicho material protegido por derechos de autor, tal y como se establece en la secci\u00f3n 107 de la Ley de Derechos de Autor de los Estados Unidos. De acuerdo con el T\u00edtulo 17 U.S.C. Secci\u00f3n 107. Para m\u00e1s informaci\u00f3n, visite: http:\/\/www.law.cornell.edu\/uscode\/17\/107.shtml<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EnergiesNet.com alienta a las personas a reproducir, reimprimir, y divulgar a trav\u00e9s de los medios audiovisuales e Internet, los comentarios editoriales y de opini\u00f3n de Petroleumworld, siempre y cuando esa reproducci\u00f3n identifique, a el autor, y la fuente original, http:\/\/www.petroleumworld.com y se haga dentro de el uso normal (fair use) de la doctrina de la secci\u00f3n 107 de la Ley de derechos de autor de los Estados Unidos de Norteam\u00e9rica (US Copyright).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EnergiesNet.com 21 11 2022<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos&nbsp;sedientos del poder, los hay payasos, y hasta uno que otro estadista.&nbsp; &nbsp;La lista de requerimientos para conducir un pa\u00eds en nuestro &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/\"> <span class=\"screen-reader-text\">Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":12510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[34,45,74,33],"tags":[],"class_list":["post-12508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-voz-baja","category-noticias-diarias","category-opinion-opinion-news-guyana","category-opinion-article"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EnergiesNet\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet\" \/>\n\t\t<meta property=\"og:description\" content=\"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-20T12:20:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-11-20T15:17:01+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/\/EnergiesNet\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#blogposting\",\"name\":\"Liderazgo Pol\\u00edtico Hemisf\\u00e9rico: Seniles, Ladrones, Fan\\u00e1ticos, Payasos\\u2026Y hasta algunos estadistas - EnergiestNet\",\"headline\":\"Liderazgo Pol\\u00edtico Hemisf\\u00e9rico: Seniles, Ladrones, Fan\\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas\",\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maduro_petro_ortegaa_diaz-canel-gcoronel-1.jpg\",\"width\":600,\"height\":350},\"datePublished\":\"2022-11-20T08:20:53-04:00\",\"dateModified\":\"2022-11-20T11:17:01-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#webpage\"},\"articleSection\":\"En Voz Baja, Noticias Diarias, Opinion, Opinion News\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/#listItem\",\"name\":\"Opinion News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/#listItem\",\"position\":2,\"name\":\"Opinion News\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/en-voz-baja\\\/#listItem\",\"name\":\"En Voz Baja\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/en-voz-baja\\\/#listItem\",\"position\":3,\"name\":\"En Voz Baja\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/en-voz-baja\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#listItem\",\"name\":\"Liderazgo Pol\\u00edtico Hemisf\\u00e9rico: Seniles, Ladrones, Fan\\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/#listItem\",\"name\":\"Opinion News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#listItem\",\"position\":4,\"name\":\"Liderazgo Pol\\u00edtico Hemisf\\u00e9rico: Seniles, Ladrones, Fan\\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/en-voz-baja\\\/#listItem\",\"name\":\"En Voz Baja\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"telephone\":\"+584142763041\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/EnergiesNet-Logo-200.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#organizationLogo\",\"width\":200,\"height\":220},\"image\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\\\/EnergiesNet\",\"https:\\\/\\\/twitter.com\\\/EnergiesNet1\",\"https:\\\/\\\/www.instagram.com\\\/energiesnet\\\/\",\"https:\\\/\\\/linkedin.com\\\/in\\\/elio-ohep-a465b78\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/\",\"name\":\"EnergiesNet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"EnergiesNet\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#webpage\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/\",\"name\":\"Liderazgo Pol\\u00edtico Hemisf\\u00e9rico: Seniles, Ladrones, Fan\\u00e1ticos, Payasos\\u2026Y hasta algunos estadistas - EnergiestNet\",\"description\":\"Por Gustavo Coronel \\u00bfQui\\u00e9nes est\\u00e1n hoy al mando de los pa\\u00edses de nuestro hemisferio? La respuesta es tr\\u00e1gica: uno que otro l\\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\\u00eds en nuestro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maduro_petro_ortegaa_diaz-canel-gcoronel-1.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#mainImage\",\"width\":600,\"height\":350},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\\\/#mainImage\"},\"datePublished\":\"2022-11-20T08:20:53-04:00\",\"dateModified\":\"2022-11-20T11:17:01-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet","description":"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro","canonical_url":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#blogposting","name":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet","headline":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas","author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/11\/maduro_petro_ortegaa_diaz-canel-gcoronel-1.jpg","width":600,"height":350},"datePublished":"2022-11-20T08:20:53-04:00","dateModified":"2022-11-20T11:17:01-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#webpage"},"isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#webpage"},"articleSection":"En Voz Baja, Noticias Diarias, Opinion, Opinion News"},{"@type":"BreadcrumbList","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","position":1,"name":"Inicio","item":"https:\/\/energiesnet.com\/espanol","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/#listItem","name":"Opinion News"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/#listItem","position":2,"name":"Opinion News","item":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/en-voz-baja\/#listItem","name":"En Voz Baja"},"previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/en-voz-baja\/#listItem","position":3,"name":"En Voz Baja","item":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/en-voz-baja\/","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#listItem","name":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/#listItem","name":"Opinion News"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#listItem","position":4,"name":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas","previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/en-voz-baja\/#listItem","name":"En Voz Baja"}}]},{"@type":"Organization","@id":"https:\/\/energiesnet.com\/espanol\/#organization","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","url":"https:\/\/energiesnet.com\/espanol\/","telephone":"+584142763041","logo":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/12\/EnergiesNet-Logo-200.jpg","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#organizationLogo","width":200,"height":220},"image":{"@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/\/EnergiesNet","https:\/\/twitter.com\/EnergiesNet1","https:\/\/www.instagram.com\/energiesnet\/","https:\/\/linkedin.com\/in\/elio-ohep-a465b78"]},{"@type":"Person","@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author","url":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/","name":"EnergiesNet","image":{"@type":"ImageObject","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g","width":96,"height":96,"caption":"EnergiesNet"}},{"@type":"WebPage","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#webpage","url":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/","name":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet","description":"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/#website"},"breadcrumb":{"@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#breadcrumblist"},"author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"creator":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/11\/maduro_petro_ortegaa_diaz-canel-gcoronel-1.jpg","@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#mainImage","width":600,"height":350},"primaryImageOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/#mainImage"},"datePublished":"2022-11-20T08:20:53-04:00","dateModified":"2022-11-20T11:17:01-04:00"},{"@type":"WebSite","@id":"https:\/\/energiesnet.com\/espanol\/#website","url":"https:\/\/energiesnet.com\/espanol\/","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","inLanguage":"es-ES","publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"}}]},"og:locale":"es_ES","og:site_name":"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals","og:type":"article","og:title":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet","og:description":"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro","og:url":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/","og:image":"https:\/\/energiesnet.com\/espanol","og:image:secure_url":"https:\/\/energiesnet.com\/espanol","article:published_time":"2022-11-20T12:20:53+00:00","article:modified_time":"2022-11-20T15:17:01+00:00","article:publisher":"https:\/\/www.facebook.com\/\/EnergiesNet","twitter:card":"summary_large_image","twitter:site":"@EnergiesNet1","twitter:title":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas - EnergiestNet","twitter:description":"Por Gustavo Coronel \u00bfQui\u00e9nes est\u00e1n hoy al mando de los pa\u00edses de nuestro hemisferio? La respuesta es tr\u00e1gica: uno que otro l\u00edder es senil, hay varios muy deshonestos y hasta criminales, varios son fan\u00e1ticos sedientos del poder, los hay payasos, y hasta uno que otro estadista. La lista de requerimientos para conducir un pa\u00eds en nuestro","twitter:creator":"@EnergiesNet1","twitter:image":"https:\/\/energiesnet.com\/espanol"},"aioseo_meta_data":{"post_id":"12508","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-12-14 18:51:53","updated":"2025-06-04 13:31:46","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/\" title=\"Opinion News\">Opinion News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/en-voz-baja\/\" title=\"En Voz Baja\">En Voz Baja<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLiderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos\u2026Y hasta algunos estadistas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/energiesnet.com\/espanol"},{"label":"Opinion News","link":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/"},{"label":"En Voz Baja","link":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/en-voz-baja\/"},{"label":"Liderazgo Pol\u00edtico Hemisf\u00e9rico: Seniles, Ladrones, Fan\u00e1ticos, Payasos&#8230;Y hasta algunos estadistas","link":"https:\/\/energiesnet.com\/espanol\/liderazgo-politico-hemisferico-seniles-ladrones-fanaticos-payasos-y-hasta-algunos-estadistas\/"}],"_links":{"self":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/12508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/comments?post=12508"}],"version-history":[{"count":0,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/12508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media\/12510"}],"wp:attachment":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media?parent=12508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/categories?post=12508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/tags?post=12508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}