{"id":15553,"date":"2023-04-02T14:43:57","date_gmt":"2023-04-02T18:43:57","guid":{"rendered":"https:\/\/energiesnet.com\/espanol\/?p=15553"},"modified":"2023-04-02T14:44:01","modified_gmt":"2023-04-02T18:44:01","slug":"refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global","status":"publish","type":"post","link":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/","title":{"rendered":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2023\/04\/smoke_pollution_refinery.jpg\" alt=\"Humo contaminante de una planta. (Ciar Global)\" class=\"wp-image-15554\" width=\"712\" height=\"451\" srcset=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2023\/04\/smoke_pollution_refinery.jpg 600w, https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2023\/04\/smoke_pollution_refinery-300x190.jpg 300w\" sizes=\"(max-width: 712px) 100vw, 712px\" \/><figcaption class=\"wp-element-caption\">Humo contaminante de una planta. (Ciar Global)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ciar Global, News<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MADRID       <br>EnergiesNet.com 031 03 2023    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arbitraje confidencial presentado por Curazao Refineria di K\u00f2rsou (RdK) contra la estatal venezolana Petr\u00f3leos de Venezuela (PDVSA) por alrededor de 1.000 millones de d\u00f3lares se desarrolla en Suiza. RdK reclama el mantenimiento de la refiner\u00eda Isla en Curazao adem\u00e1s de agravios al medio ambiente tras la salida de PDVSA en 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras meses de negociaci\u00f3n entre las partes sin acuerdo, la tambi\u00e9n estatal RdK interpuso el arbitraje en una corte de arbitraje de Suiza. Por su lado, PDVSA tambi\u00e9n reclama una indemnizaci\u00f3n a la refiner\u00eda curazole\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Demandas sobre los agravios al medioambiente<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los habitantes de Curazao lucharon durante a\u00f1os para que PDVSA entregara la planta en 2019 al expirar su contrato, el movimiento incluso lleg\u00f3 a la pol\u00edtica con un grupo expresamente formado para pedir la salida de la venezolana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2009 un tribunal curazole\u00f1o concluy\u00f3 que PDVSA deb\u00eda modernizar las instalaciones para cumplir con las exigencias medioambientales. Se acusaba a la venezolana de contaminaci\u00f3n de suelos, vertederos no controlados o mal tratamiento de residuos (ver \u201c<a href=\"https:\/\/www.reuters.com\/article\/petroleo-curazao-refineria-idARN1628605020110316\" target=\"_blank\" rel=\"noreferrer noopener\">ENFOQUE-Refiner\u00eda Isla, un hu\u00e9sped que incomoda en Curazao<\/a>\u201c, Marianna P\u00e1rraga, Reuters, 16.03.2011).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La contaminaci\u00f3n de la refiner\u00eda ha sido denunciada durante a\u00f1os por la proximidad a las zonas de habitabilidad de miles de personas amenazadas por las emisiones de di\u00f3xido de azufre y otros materiales t\u00f3xicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El otro arbitraje RdK-PDVSA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En marzo de 2020 RdK solicit\u00f3 un arbitraje contra PDVSA ante el&nbsp;<strong>International Centre for Dispute Resolution (ICDR)<\/strong>&nbsp;en EE.UU. por la gesti\u00f3n llevada a cabo por la venezolana en la refiner\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante ese mes, Curazao incaut\u00f3 una terminal de almacenamiento de petr\u00f3leo propiedad de PDVSA en Bonaire para hacer cumplir reclamaciones por pagos vencidos, costes de mantenimiento y da\u00f1os ambientales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ciarglobal.com 09 02 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/\"> <span class=\"screen-reader-text\">Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":15554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[45],"tags":[1064,229,1066,107,1045],"class_list":["post-15553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-diarias","tag-arbitraje","tag-contaminacion","tag-curazao-refineria-di-korsou","tag-pdvsa","tag-rdk"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EnergiesNet\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet\" \/>\n\t\t<meta property=\"og:description\" content=\"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-02T18:43:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-04-02T18:44:01+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/\/EnergiesNet\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#blogposting\",\"name\":\"Refiner\\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \\u2013 Ciar Global - EnergiestNet\",\"headline\":\"Refiner\\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global\",\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/smoke_pollution_refinery.jpg\",\"width\":600,\"height\":380},\"datePublished\":\"2023-04-02T14:43:57-04:00\",\"dateModified\":\"2023-04-02T14:44:01-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#webpage\"},\"articleSection\":\"Noticias Diarias, arbitraje, contaminacion, Curazao Refineria di K\\u00f2rsou, pdvsa, Rdk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/#listItem\",\"name\":\"Noticias Diarias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/#listItem\",\"position\":2,\"name\":\"Noticias Diarias\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#listItem\",\"name\":\"Refiner\\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#listItem\",\"position\":3,\"name\":\"Refiner\\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/#listItem\",\"name\":\"Noticias Diarias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"telephone\":\"+584142763041\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/EnergiesNet-Logo-200.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#organizationLogo\",\"width\":200,\"height\":220},\"image\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\\\/EnergiesNet\",\"https:\\\/\\\/twitter.com\\\/EnergiesNet1\",\"https:\\\/\\\/www.instagram.com\\\/energiesnet\\\/\",\"https:\\\/\\\/linkedin.com\\\/in\\\/elio-ohep-a465b78\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/\",\"name\":\"EnergiesNet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"EnergiesNet\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#webpage\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/\",\"name\":\"Refiner\\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \\u2013 Ciar Global - EnergiestNet\",\"description\":\"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\\u00f2rsou y Petr\\u00f3leos de Venezuela est\\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\\u00eda Isla y da\\u00f1os al medioambiente, tras su salida hace cuatro a\\u00f1os largamente perseguida por grupos ambientalistas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/smoke_pollution_refinery.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#mainImage\",\"width\":600,\"height\":380},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\\\/#mainImage\"},\"datePublished\":\"2023-04-02T14:43:57-04:00\",\"dateModified\":\"2023-04-02T14:44:01-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet","description":"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.","canonical_url":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#blogposting","name":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet","headline":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global","author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2023\/04\/smoke_pollution_refinery.jpg","width":600,"height":380},"datePublished":"2023-04-02T14:43:57-04:00","dateModified":"2023-04-02T14:44:01-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#webpage"},"isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#webpage"},"articleSection":"Noticias Diarias, arbitraje, contaminacion, Curazao Refineria di K\u00f2rsou, pdvsa, Rdk"},{"@type":"BreadcrumbList","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","position":1,"name":"Inicio","item":"https:\/\/energiesnet.com\/espanol","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/#listItem","name":"Noticias Diarias"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/#listItem","position":2,"name":"Noticias Diarias","item":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#listItem","name":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global"},"previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#listItem","position":3,"name":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global","previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/#listItem","name":"Noticias Diarias"}}]},{"@type":"Organization","@id":"https:\/\/energiesnet.com\/espanol\/#organization","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","url":"https:\/\/energiesnet.com\/espanol\/","telephone":"+584142763041","logo":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/12\/EnergiesNet-Logo-200.jpg","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#organizationLogo","width":200,"height":220},"image":{"@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/\/EnergiesNet","https:\/\/twitter.com\/EnergiesNet1","https:\/\/www.instagram.com\/energiesnet\/","https:\/\/linkedin.com\/in\/elio-ohep-a465b78"]},{"@type":"Person","@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author","url":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/","name":"EnergiesNet","image":{"@type":"ImageObject","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g","width":96,"height":96,"caption":"EnergiesNet"}},{"@type":"WebPage","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#webpage","url":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/","name":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet","description":"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/#website"},"breadcrumb":{"@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#breadcrumblist"},"author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"creator":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2023\/04\/smoke_pollution_refinery.jpg","@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#mainImage","width":600,"height":380},"primaryImageOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/#mainImage"},"datePublished":"2023-04-02T14:43:57-04:00","dateModified":"2023-04-02T14:44:01-04:00"},{"@type":"WebSite","@id":"https:\/\/energiesnet.com\/espanol\/#website","url":"https:\/\/energiesnet.com\/espanol\/","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","inLanguage":"es-ES","publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"}}]},"og:locale":"es_ES","og:site_name":"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals","og:type":"article","og:title":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet","og:description":"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.","og:url":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/","og:image":"https:\/\/energiesnet.com\/espanol","og:image:secure_url":"https:\/\/energiesnet.com\/espanol","article:published_time":"2023-04-02T18:43:57+00:00","article:modified_time":"2023-04-02T18:44:01+00:00","article:publisher":"https:\/\/www.facebook.com\/\/EnergiesNet","twitter:card":"summary_large_image","twitter:site":"@EnergiesNet1","twitter:title":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global - EnergiestNet","twitter:description":"Ciar Global, News MADRID EnergiesNet.com 031 03 2023 Curazao Refineria di K\u00f2rsou y Petr\u00f3leos de Venezuela est\u00e1n inmersas en un nuevo arbitraje en el que la estatal curazole\u00f1a demanda a la estatal venezolana el no mantenimiento de la refiner\u00eda Isla y da\u00f1os al medioambiente, tras su salida hace cuatro a\u00f1os largamente perseguida por grupos ambientalistas.","twitter:creator":"@EnergiesNet1","twitter:image":"https:\/\/energiesnet.com\/espanol"},"aioseo_meta_data":{"post_id":"15553","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-04-02 18:44:04","updated":"2025-06-04 14:38:40","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/\" title=\"Noticias Diarias\">Noticias Diarias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRefiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza \u2013 Ciar Global\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/energiesnet.com\/espanol"},{"label":"Noticias Diarias","link":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/"},{"label":"Refiner\u00eda De Curazao Abre Nuevo Arbitraje Contra PDVSA En Suiza &#8211; Ciar Global","link":"https:\/\/energiesnet.com\/espanol\/refineria-de-curazao-abre-nuevo-arbitraje-contra-pdvsa-en-suiza-ciar-global\/"}],"_links":{"self":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/15553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/comments?post=15553"}],"version-history":[{"count":0,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/15553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media\/15554"}],"wp:attachment":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media?parent=15553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/categories?post=15553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/tags?post=15553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}