{"id":21337,"date":"2024-04-29T15:21:34","date_gmt":"2024-04-29T19:21:34","guid":{"rendered":"https:\/\/energiesnet.com\/espanol\/?p=21337"},"modified":"2024-04-29T15:36:32","modified_gmt":"2024-04-29T19:36:32","slug":"oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho","status":"publish","type":"post","link":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/","title":{"rendered":"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\u00a0"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2024\/04\/oppenheimer_black_board_.jpg\" alt=\"\" class=\"wp-image-21338\" srcset=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2024\/04\/oppenheimer_black_board_.jpg 600w, https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2024\/04\/oppenheimer_black_board_-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.google.com\/url?sa=t&amp;source=web&amp;rct=j&amp;opi=89978449&amp;url=https:\/\/es.wikipedia.org\/wiki\/Robert_Oppenheimer&amp;ved=2ahUKEwjeg7LGkOiFAxWNMVkFHdLuCUIQh-wKegQIDxAC&amp;usg=AOvVaw3S8NrY1R0MAsObC98kOuBC\" target=\"_blank\" rel=\"noreferrer noopener\">Robert Oppenheimer<\/a> (John Rooney\/AP\/SIPA)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por Frank Bracho         <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d\u00a0-Gandhi<\/em>   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nombre \u00abOppenheimer\u00bb, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva letal terrible bomba nuclear que luego devastar\u00eda a Hiroshima y Nagasaki en Jap\u00f3n, ha sido puesto de nuevo \u00abde moda\u00bb por la pel\u00edcula del mismo nombre ! -que ha sido el gran \u00e9xito mundial sin precedentes del a\u00f1o pasado !!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;La verdad es que al comienzo pocos hab\u00edan apostado a esto !!..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para un tan largo detallado film que, en forma mani\u00e1tica, misional, fiel, se dedica a narrar la saga cient\u00edfica de c\u00f3mo se hizo dicha Bomba !&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trataba, adem\u00e1s, de algo que luc\u00eda demasiado t\u00e9cnico y, hasta ahora, -por razones obvias- tomado por \u00ablas \u00e9lites mundiales\u00bb como \u00abun coto de o informaci\u00f3n secreta farragosa, y de indudables Implicaciones \u00e9ticas controversiales\u00bb&#8230;sobre lo cual, se prefer\u00eda no hablar mucho en p\u00fablico !&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, tanto los productores de la pel\u00edcula, quiz\u00e1s \u00absin querer queriendo\u00bb como el asustado y hambriento de Verdad p\u00fablico de Hoy, \u00abse enlazaron\u00bb entre s\u00ed ! &#8230;para ocasionar el \u00abfen\u00f3meno comunicacional universal\u00bb en que se ha convertido Hoy este film ! -Y todos los temas de fondo que evoca !!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;Temas tales como: El escenario de una gran posible nueva guerra mundial catastr\u00f3fica desbocada&#8230; Todo lo que son&nbsp; capaces de hacer o apoyar \u00abminor\u00edas o mayor\u00edas\u00bb -cient\u00edficas, militares, econ\u00f3micas, o de opini\u00f3n p\u00fablica- que puedan sentirse \u00abdesafiadas, perseguidas, discriminadas o&nbsp; amenazadas\u00bb(!) ..El que haya sido el mismo Presidente Truman de EEUU -que brind\u00f3 generosa hospitalidad a la creaci\u00f3n de la ONU en San Francisco, California, en 1945, el mismo que m\u00e1s luego arrojar\u00eda las terribles nuevas bombas sobre el empecinado guerrerista Jap\u00f3n (!) &#8230;Y los perennes grandes temas de \u00abla legitimidad de la masiva violencia o fuerza vs la no violencia de la compasi\u00f3n o escrupulosidad de toda sagrada vida\u00bb !&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre todos esos Temas hemos estado reflexionando mucho y discurriendo tanto en lo personal privado como en la <em>Web<\/em> !! &#8230;Pues entendemos que son parte insoslayable de una agenda universal que hoy toca asumir, ante tanta incertidumbre o tribulaci\u00f3n \u00abtipo tic tac\u00bb que Hoy nos embarga !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&#8230;Y para una sociedad que se siente \u00abdesbrujulada\u00bb, para Hoy bien asumir Todo lo anterior&nbsp; ! &#8230;.Y la cual, en el fondo, mucho necesita darle el correcto sentido a todo lo actualmente en juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;Y ante lo cual, aun en los escenarios de mayor depuraci\u00f3n que parecen inexorablemente avecinarse, no queda otra que Volver a acogernos a los ignotos designios misericordiosos y alqu\u00edmicos divinos ! &#8230;Acogi\u00e9ndonos a la famosa frase de fe, calma y esperanza pr\u00e1ctica interior de los Luther King, Gandhi y Einstein, de Hoy: \u00ab<em>Aun si yo supiera que el actual mundo se acabar\u00eda ma\u00f1ana, plantar\u00eda, jubiloso, un \u00e1rbol Hoy !\u00bb<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temas, todos, que han sido magistralmente tratados en el contiguo abajo art\u00edculo de un veterano analista internacional, hablando del fen\u00f3meno de la pel\u00edcula Oppenheimer. (!!)&nbsp; (&#8230;De cara a los terribles actuales conflictos de potencial mundial -como los de <em>Ucrania<\/em> y el <em>Medio<\/em> <em>Oriente<\/em>, en los cuales no s\u00f3lo ya habido el tan doloroso &#8211; y muy dif\u00edcil de aceptar-&nbsp; efecto de aparentemente&nbsp; estarlo pagando en grande \u00abjustos por pecadores\u00bb(!) &#8230;Sino que se ha blandido de nuevo la opci\u00f3n nuclear (!!)&nbsp; (&#8230;ya no s\u00f3lo al alcance de \u00abun club de naciones\u00bb supuestas&nbsp; \u00abadministradoras\u00bb&#8230; sino de grupos extremistas incontrolables !), y se han usado \u00abnuevas tecnolog\u00edas rob\u00f3ticas\u00bb \u00aba\u00fan m\u00e1s deshumanizadoras de guerras a fondo sin fin\u00bb !&nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230; Articulo magistral que nos hemos tomado la libertad de traducir al Espa\u00f1ol, resaltando algunas frases ! Luego de haberlo distribuido&nbsp; ampliamente por nuestra parte en Ingl\u00e9s -con un \u00abComentario\u00bb nuestro, que no s\u00f3lo se hace eco de incluir tambi\u00e9n \u00abel punto de vista de los que fueron masivamente exterminados por las Bombas\u00bb , sino tambi\u00e9n el de incluir tambi\u00e9n \u00abel punto de vista de la materia prima del <em>uranio<\/em> <em>de<\/em> <em>sangre<\/em>\u00bb &#8211; extra\u00eddo del <em>Congo<\/em>&nbsp;-de una pavorosa guerra interna depredadora -la cual se llev\u00f3 hasta \u00abpor los cachos\u00bb a un l\u00edder \u00e9tico mediador de la ONU tan brillante y promisorio como <em>Dag<\/em> <em>Hammarksjold<\/em> <em>!&nbsp;<\/em>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Traducci\u00f3n informal del Original en Ingl\u00e9s &#8211; resaltados, nuestros)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CUANDO EL HOMBRE QUE CONSTRUY\u00d3 LAS BOMBAS CONOCI\u00d3 AL HOMBRE QUE LANZO LAS BOMBAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<em>Thalif Deen *<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>&nbsp;<\/em><\/strong>(NACIONES UNIDAS, abril 2024 (IPS) La premiada pel\u00edcula de Hollywood \u201cOPPENHEIMER\u201d retrata la vida de Julius Robert Oppenheimer, quien ayud\u00f3 a crear la bomba at\u00f3mica, que se cobr\u00f3 la vida de entre 140.000 y 226.000 personas y devast\u00f3 las dos ciudades japonesas de Hiroshima y Nagasaki, en agosto de 1945).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La tragedia se describi\u00f3 como \u00abun desastre humanitario de proporciones b\u00edblicas\u00bb !!&nbsp; Pero la pel\u00edcula se centra en la creaci\u00f3n de las bombas, no en la devastaci\u00f3n que causaron !!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En un art\u00edculo de la revista Time del pasado mes de febrero, Jeffrey Kluger relata una reuni\u00f3n en la Casa Blanca entre el Presidente de EEUU Harry S. Truman y Oppenheimer describi\u00e9ndola acertadamente como \u00abel hombre que construy\u00f3 las bombas y el hombre que lanz\u00f3 las bombas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Aquejado de una culpa imperdonable, Oppenheimer, seg\u00fan se dice, le dijo a Truman: \u00abSe\u00f1or Presidente, siento que tengo las manos manchadas de sangre\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la historia recuerda una manera diferente lo que ocurri\u00f3, a continuaci\u00f3n, dice Time.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Al parecer, Truman dijo: \u00abNo importa, sal a lav\u00e1rtelas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&#8230;U otra versi\u00f3n hist\u00f3rica, en la que un impenitente Truman le entrega un pa\u00f1uelo a Oppenheimer y le dice: \u00abBueno, toma, \u00bfquieres limpiarte las manos?\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En la pel\u00edcula, Truman se limita a blandir el pa\u00f1uelo.(!!).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un antiguo Alcalde de Hiroshima, Takashi Hiraoka, que habl\u00f3 en un preestreno de la pel\u00edcula, fue m\u00e1s cr\u00edtico con lo que se omiti\u00f3 en la pel\u00edcula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Se le cit\u00f3 diciendo: \u00abDesde el punto de vista de Hiroshima, no se represent\u00f3 suficientemente el horror de las armas nucleares. La pel\u00edcula se hizo de forma que validara la conclusi\u00f3n de que la bomba at\u00f3mica se utiliz\u00f3 para salvar las vidas de los estadounidenses\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La Campa\u00f1a Internacional para la Abolici\u00f3n de las Armas Nucleares (ICAN) afirm\u00f3 que el estreno de la pel\u00edcula de Oppenheimer, y la oleada de atenci\u00f3n (medi\u00e1tica) que la rodea, crea una oportunidad para despertar la atenci\u00f3n p\u00fablica sobre los riesgos de las armas nucleares e invitar a nuevos p\u00fablicos a implicarse en el movimiento para abolir las armas nucleares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u00abPodemos educar sobre los riesgos y compartir un mensaje muy necesario de esperanza y resistencia: Oppenheimer trata de c\u00f3mo empezaron las armas nucleares, el Tratado de la ONU sobre la Prohibici\u00f3n de las Armas Nucleares (TPNW) que apunta a c\u00f3mo acabamos con ellas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En cuanto a la perspectiva hist\u00f3rica, el Dr. Alon Ben-Meir, profesor jubilado de relaciones internacionales en el Centro de Asuntos Globales de la Universidad de Nueva York (NYU), dijo a IPS que el \u201c<strong>Proyecto Manhattan\u201d,<\/strong> que fue encabezado por Oppenheimer para desarrollar un arma nuclear, comenz\u00f3 mientras la Segunda Guerra Mundial hac\u00eda estragos y Alemania estaba en marcha, conquistando un pa\u00eds tras otro en Europa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Sin embargo, cuando se desarroll\u00f3 el arma nuclear, Alemania se hab\u00eda rendido, pero Jap\u00f3n sigui\u00f3 luchando !! Seg\u00fan relatos hist\u00f3ricos documentados, las fuerzas japonesas luchaban en todas las trincheras, en todos los frentes, hasta el \u00faltimo soldado, y la palabra \u00abrendici\u00f3n\u00bb no estaba en su vocabulario, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El General Marshall, que era Jefe del Estado Mayor del Ej\u00e9rcito de EEUU, aconsej\u00f3 al Presidente Truman en aquel momento que, si la guerra continuaba durante uno o dos a\u00f1os m\u00e1s, cientos de miles de soldados estadounidenses y quiz\u00e1s m\u00e1s de un mill\u00f3n de japoneses morir\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Cuando Truman le pregunt\u00f3 qu\u00e9 sugerir\u00eda, el general Marshall y otros, le indicaron que bombardear uno o incluso dos emplazamientos en Jap\u00f3n con un arma nuclear podr\u00eda llevar la guerra a una r\u00e1pida conclusi\u00f3n y salvar las vidas de millones de personas de ambos bandos.(!!)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, se convenci\u00f3 a Truman de que \u00e9sta pod\u00eda ser la \u00fanica soluci\u00f3n, sobre todo teniendo en cuenta que los japoneses estaban decididos a luchar hasta el amargo final, dijo Ben-Meir, que imparti\u00f3 cursos sobre negociaci\u00f3n internacional, y estudios sobre el Oriente Medio, durante m\u00e1s de 20 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u00abUna vez que se lanzaron las bombas y Oppenheimer se dio cuenta de la magnitud de los da\u00f1os y las muertes que se produjeron en Hiroshima y Nagasaki, \u00e9l se sinti\u00f3 personalmente responsable del impacto catastr\u00f3fico de la bomba, declar\u00e1ndole al presidente Truman que \u00absent\u00eda que ten\u00eda las manos manchadas de sangre por lo sucedido\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Truman le dijo entonces a Oppenheimer que, aunque el cient\u00edfico hab\u00eda estado detr\u00e1s del desarrollo del arma nuclear, la decisi\u00f3n de utilizarla era suya, y que Oppenheimer no ten\u00eda responsabilidad alguna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El Presidente Truman supuestamente le entreg\u00f3 a Oppenheimer su pa\u00f1uelo para que presumiblemente se limpiara las manos de las manchas de sangre. Sin embargo, Oppenheimer abandon\u00f3 el Despacho del presidente completamente consternado, dijo Ben-Meir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u00abLos japoneses no creen que Truman estuviera preocupado por la posible p\u00e9rdida de vidas japonesas si la guerra hubiera continuado, sino que estaba preocupado principalmente por las vidas estadounidenses. Lamentablemente, esto sigue siendo un punto de discordia, pero se super\u00f3 en su mayor parte gracias a la s\u00f3lida alianza que se desarroll\u00f3 posteriormente entre EEUU y Jap\u00f3n.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Por supuesto, lo que agrav\u00f3 la profunda desesperaci\u00f3n de Oppenheimer fue lo sucedido posteriormente al ser acusado de ser miembro del Partido Comunista y revoc\u00e1rsele la \u201cTarjeta de Seguridad\u201d, lo cual puso fin a su trabajo con el gobierno estadounidense ! (aunque fue exonerado a t\u00edtulo p\u00f3stumo), declar\u00f3 Ben-Meir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En general, sin embargo, seg\u00fan la Radio P\u00fablica Nacional (NPR), muchos espectadores japoneses expresaron su malestar con la narraci\u00f3n de Oppenheimer y sintieron que el retrato de la pel\u00edcula era incompleto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTsuyuko Iwanai, residente en Nagasaki, declar\u00f3 a la NPR: \u00abLa pel\u00edcula s\u00f3lo habla del bando que lanz\u00f3 la bomba at\u00f3mica. \u00abOjal\u00e1 hubieran incluido el bando sobre el cual fue lanzada\u00bb. (!!!)&#8230;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Al presenciar el \u00e9xito de la primera prueba nuclear, Oppenheimer cit\u00f3 una frase del \u201c<em>Bhagavad Gita\u201d<\/em> : <em>\u201c<\/em><strong><em>Ahora soy la Muerte: el destructor de los mundos\u00bb,<\/em><\/strong><strong> <\/strong>seg\u00fan UNFOLD ZERO, una plataforma de iniciativas y acciones centradas en la ONU para la consecuci\u00f3n de un mundo libre de armas nucleares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u00abDe hecho, Oppenheimer qued\u00f3 tan impactado por el potencial de la bomba nuclear para destruir el mundo que, tras el final de la Segunda Guerra Mundial, se implic\u00f3 profundamente en el control internacional de las armas nucleares, la paz y la promoci\u00f3n de la gobernanza mundial\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong>\u201cLa pel\u00edcula deber\u00eda recordarnos lo importantes y pertinentes que son estas ideas hoy en d\u00eda, cuando las guerras se recrudecen, las tensiones entre Estados con armas nucleares aumentan y la amenaza de una guerra nuclear es m\u00e1s alta que nunca\u201d,<\/strong> afirm\u00f3 UNFOLD ZERO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl pensamiento, la pasi\u00f3n y el compromiso de Oppenheimer en relaci\u00f3n con estas cuestiones apenas se tocan en la pel\u00edcula, a pesar de ser tan importante hoy en d\u00eda volver a despertar nuestra comprensi\u00f3n colectiva de la naturaleza de la disuasi\u00f3n nuclear, los riesgos del nacionalismo y la importancia de fortalecer el estado de derecho, prevenir la guerra nuclear y lograr la paz a trav\u00e9s de la gobernanza mundial.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Secretario General Ant\u00f3nio Guterres, en su intervenci\u00f3n ante el Consejo de Seguridad de la <em>ONU<\/em>, el pasado 18 de marzo, se refiri\u00f3 a la pel\u00edcula, que gan\u00f3 siete Oscar en la Ceremonia de Entrega de los Premios de la Academia de Hollywood, el 10 de marzo, incluidos los cuatro premios principales a la Mejor Pel\u00edcula, el Mejor Director, el Mejor Actor y el Mejor Actor de Reparto, expres\u00f3 lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u00abEl Reloj del Juicio Final est\u00e1 sonando lo suficientemente fuerte como para que todos lo oigan. Desde acad\u00e9micos y grupos de la sociedad civil, piden el fin de la locura nuclear\u00bb, y luego hizo un ardiente llamado:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u00abAl <em>Papa Francisco<\/em>, que califica de &#8216;<em><u>inmoral<\/u><\/em>&#8216; la posesi\u00f3n de armas nucleares. A los j\u00f3venes de todo el mundo que preocupados por su futuro exigen un cambio. A los Hibakusha, los valientes supervivientes de Hiroshima y Nagasaki -entre nuestros mayores ejemplos vivientes para decir la Verdad al Poder- les pido que transmitan su eterno mensaje de Paz\u00bb\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLa humanidad no puede sobrevivir a una secuela de Oppenheimer\u201d, <\/strong>advirti\u00f3 <em>Guterres<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; \u00a0*Ex Jefe de la Oficina de la ONU y Director Regional de <em>IPS North America,<\/em> ha estado cubriendo la ONU desde finales de la d\u00e9cada de 1970. Ex Subdirector de Noticias del <em>Sri Lanka Daily News<\/em>, fue redactor jefe del diario de <em>Hong Kong The Standard<\/em>.\u00a0 Este art\u00edculo ha sido elaborado por <em>IPS Noram<\/em>, en colaboraci\u00f3n con <em>INPS Japan<\/em> y <em>Soka Gakkai International<\/em>, con estatus consultivo ante el ECOSOC de la ONU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">____________________________________________<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Frank Bracho<\/em><\/strong> es activista de la sociedad civil; Tambi\u00e9n ha tenido una intensa y variada experiencia como autor, conferenciante y activista en la sociedad civil y en movimientos de defensa en temas de cambio de civilizaci\u00f3n. Los puntos de vista expresados no necesariamente son los de EnergiesNet.com.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nota del Editor:\u00a0Este art\u00edculo fue originalmente publicado en\u00a0Reporte Cat\u00f3lico Laico (RCL)<em><a href=\"http:\/\/lasarmasdecoronel.blogspot.com\/\">\u00a0<\/a><\/em>el 15 de abril del 2024 Reproducimos el mismo en beneficio de los lctores.\u00a0EnergiesNet.com no se hace responsable por los juicios de valor emitidos por sus colaboradores y columnistas de opini\u00f3n y an\u00e1lisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aviso de uso: Este sitio contiene material protegido por derechos de autor cuyo uso no siempre ha sido espec\u00edficamente autorizado por el propietario de los derechos. Ponemos a disposici\u00f3n dicho material en nuestro esfuerzo por avanzar en la comprensi\u00f3n de cuestiones de importancia social, medioambiental y humanitaria. Creemos que esto constituye un \u00abuso justo\u00bb de cualquier material protegido por derechos de autor, tal como se establece en la secci\u00f3n 107 de la Ley de Derechos de Autor de EE.UU.. De acuerdo con el T\u00edtulo 17 U.S.C. Secci\u00f3n 107. Para m\u00e1s informaci\u00f3n, visite: http:\/\/www.law.cornell.edu\/uscode\/17\/107.shtml.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EnergiesNet.com 29 04 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d\u00a0-Gandhi El nombre \u00abOppenheimer\u00bb, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/\"> <span class=\"screen-reader-text\">Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\u00a0<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":21338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[41,45,33],"tags":[3278,3583,3584],"class_list":["post-21337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-invitados","category-noticias-diarias","category-opinion-article","tag-frank-bracho","tag-oppenheimer","tag-profecias-mundiales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre &quot;Oppenheimer&quot;, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EnergiesNet\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet\" \/>\n\t\t<meta property=\"og:description\" content=\"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre &quot;Oppenheimer&quot;, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-29T19:21:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-29T19:36:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/\/EnergiesNet\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre &quot;Oppenheimer&quot;, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#blogposting\",\"name\":\"Oppenheimer y las actuales profecias mundiales \\u2013 Frank Bracho - EnergiestNet\",\"headline\":\"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\\u00a0\",\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/oppenheimer_black_board_.jpg\",\"width\":600,\"height\":400},\"datePublished\":\"2024-04-29T15:21:34-04:00\",\"dateModified\":\"2024-04-29T15:36:32-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#webpage\"},\"articleSection\":\"Invitados, Noticias Diarias, Opinion News, frank bracho, Oppenheimer, profecias mundiales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/#listItem\",\"name\":\"Opinion News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/#listItem\",\"position\":2,\"name\":\"Opinion News\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/invitados\\\/#listItem\",\"name\":\"Invitados\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/invitados\\\/#listItem\",\"position\":3,\"name\":\"Invitados\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/invitados\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#listItem\",\"name\":\"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\\u00a0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/#listItem\",\"name\":\"Opinion News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#listItem\",\"position\":4,\"name\":\"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\\u00a0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/opinion-article\\\/invitados\\\/#listItem\",\"name\":\"Invitados\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"telephone\":\"+584142763041\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/EnergiesNet-Logo-200.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#organizationLogo\",\"width\":200,\"height\":220},\"image\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\\\/EnergiesNet\",\"https:\\\/\\\/twitter.com\\\/EnergiesNet1\",\"https:\\\/\\\/www.instagram.com\\\/energiesnet\\\/\",\"https:\\\/\\\/linkedin.com\\\/in\\\/elio-ohep-a465b78\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/\",\"name\":\"EnergiesNet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"EnergiesNet\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#webpage\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/\",\"name\":\"Oppenheimer y las actuales profecias mundiales \\u2013 Frank Bracho - EnergiestNet\",\"description\":\"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\\u00f3n y del esp\\u00edritu de violencia, del que la guerra es la expresi\\u00f3n natural y la bomba at\\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\\u201d -Gandhi El nombre \\\"Oppenheimer\\\", del cient\\u00edfico alem\\u00e1n jud\\u00edo que dise\\u00f1\\u00f3 la masiva\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/oppenheimer_black_board_.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#mainImage\",\"width\":600,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\\\/#mainImage\"},\"datePublished\":\"2024-04-29T15:21:34-04:00\",\"dateModified\":\"2024-04-29T15:36:32-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet","description":"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre \"Oppenheimer\", del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva","canonical_url":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#blogposting","name":"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet","headline":"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\u00a0","author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2024\/04\/oppenheimer_black_board_.jpg","width":600,"height":400},"datePublished":"2024-04-29T15:21:34-04:00","dateModified":"2024-04-29T15:36:32-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#webpage"},"isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#webpage"},"articleSection":"Invitados, Noticias Diarias, Opinion News, frank bracho, Oppenheimer, profecias mundiales"},{"@type":"BreadcrumbList","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","position":1,"name":"Inicio","item":"https:\/\/energiesnet.com\/espanol","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/#listItem","name":"Opinion News"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/#listItem","position":2,"name":"Opinion News","item":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/invitados\/#listItem","name":"Invitados"},"previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/invitados\/#listItem","position":3,"name":"Invitados","item":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/invitados\/","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#listItem","name":"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\u00a0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/#listItem","name":"Opinion News"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#listItem","position":4,"name":"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\u00a0","previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/invitados\/#listItem","name":"Invitados"}}]},{"@type":"Organization","@id":"https:\/\/energiesnet.com\/espanol\/#organization","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","url":"https:\/\/energiesnet.com\/espanol\/","telephone":"+584142763041","logo":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/12\/EnergiesNet-Logo-200.jpg","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#organizationLogo","width":200,"height":220},"image":{"@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/\/EnergiesNet","https:\/\/twitter.com\/EnergiesNet1","https:\/\/www.instagram.com\/energiesnet\/","https:\/\/linkedin.com\/in\/elio-ohep-a465b78"]},{"@type":"Person","@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author","url":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/","name":"EnergiesNet","image":{"@type":"ImageObject","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g","width":96,"height":96,"caption":"EnergiesNet"}},{"@type":"WebPage","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#webpage","url":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/","name":"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet","description":"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre \"Oppenheimer\", del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/#website"},"breadcrumb":{"@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#breadcrumblist"},"author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"creator":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2024\/04\/oppenheimer_black_board_.jpg","@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#mainImage","width":600,"height":400},"primaryImageOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/#mainImage"},"datePublished":"2024-04-29T15:21:34-04:00","dateModified":"2024-04-29T15:36:32-04:00"},{"@type":"WebSite","@id":"https:\/\/energiesnet.com\/espanol\/#website","url":"https:\/\/energiesnet.com\/espanol\/","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","inLanguage":"es-ES","publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"}}]},"og:locale":"es_ES","og:site_name":"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals","og:type":"article","og:title":"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet","og:description":"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre &quot;Oppenheimer&quot;, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva","og:url":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/","og:image":"https:\/\/energiesnet.com\/espanol","og:image:secure_url":"https:\/\/energiesnet.com\/espanol","article:published_time":"2024-04-29T19:21:34+00:00","article:modified_time":"2024-04-29T19:36:32+00:00","article:publisher":"https:\/\/www.facebook.com\/\/EnergiesNet","twitter:card":"summary_large_image","twitter:site":"@EnergiesNet1","twitter:title":"Oppenheimer y las actuales profecias mundiales \u2013 Frank Bracho - EnergiestNet","twitter:description":"Por Frank Bracho A menos que las grandes naciones se despojen de su deseo de explotaci\u00f3n y del esp\u00edritu de violencia, del que la guerra es la expresi\u00f3n natural y la bomba at\u00f3mica la consecuencia inevitable, no hay esperanza de paz en el mundo\u201d -Gandhi El nombre &quot;Oppenheimer&quot;, del cient\u00edfico alem\u00e1n jud\u00edo que dise\u00f1\u00f3 la masiva","twitter:creator":"@EnergiesNet1","twitter:image":"https:\/\/energiesnet.com\/espanol"},"aioseo_meta_data":{"post_id":"21337","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-29 19:21:46","updated":"2025-06-04 16:34:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/\" title=\"Opinion News\">Opinion News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/invitados\/\" title=\"Invitados\">Invitados<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOppenheimer y las actuales profecias mundiales \u2013 Frank Bracho \n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/energiesnet.com\/espanol"},{"label":"Opinion News","link":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/"},{"label":"Invitados","link":"https:\/\/energiesnet.com\/espanol\/category\/opinion-article\/invitados\/"},{"label":"Oppenheimer y las actuales profecias mundiales &#8211; Frank Bracho\u00a0","link":"https:\/\/energiesnet.com\/espanol\/oppenheimer-y-las-actuales-profecias-mundiales-frank-bracho\/"}],"_links":{"self":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/21337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/comments?post=21337"}],"version-history":[{"count":0,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/21337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media\/21338"}],"wp:attachment":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media?parent=21337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/categories?post=21337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/tags?post=21337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}