{"id":24623,"date":"2025-01-21T11:27:06","date_gmt":"2025-01-21T15:27:06","guid":{"rendered":"https:\/\/energiesnet.com\/espanol\/?p=24623"},"modified":"2025-01-21T11:36:00","modified_gmt":"2025-01-21T15:36:00","slug":"pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones","status":"publish","type":"post","link":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/","title":{"rendered":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gesti\u00f3n de PDVSA Ad Hoc y CITGO  durante 2024<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"367\" src=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2025\/01\/pdvsa_ad-hoc.jpg\" alt=\"CITGO continua operando con resultados positivos\" class=\"wp-image-24624\" style=\"width:610px;height:auto\" srcset=\"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2025\/01\/pdvsa_ad-hoc.jpg 600w, https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2025\/01\/pdvsa_ad-hoc-300x184.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">CITGO contin\u00faa operando con resultados positivos<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">EnergiesNet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CARACAS           <br>EnergiesNet.com 21 01 2025        <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los 20 mil millones de d\u00f3lares, derivadas principalmente de expropiaciones y deudas contra\u00eddas por los negligentes reg\u00edmenes de Hugo Ch\u00e1vez y Nicol\u00e1s Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2018, la Corte de Distrito de Delaware impuso un embargo sobre las acciones de PDVSA en PDV Holding (PDVH), propietaria indirecta de la refiner\u00eda CITGO, desarrollando un complejo proceso judicial bajo la supervisi\u00f3n del Juez Federal Leonard Stark. Este proceso contin\u00faa activo en la etapa de una venta forzada de acciones, que se encuentra enmarcado en m\u00faltiples asuntos procesales y comerciales a\u00fan por resolver, incluyendo objeciones y la posibilidad de apelaciones por parte de las entidades venezolanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la complejidad de las circunstancias judiciales, PDVSA Ad Hoc mantiene la disposici\u00f3n de cooperar con mecanismos alternativos que puedan ser propuestos por las partes implicadas en el proceso para cumplir con las obligaciones financieras y evitar la venta forzada, una vez se logre una transici\u00f3n democr\u00e1tica en Venezuela. En este contexto, CITGO sigue siendo un activo fundamental y de alto valor para PDVSA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la Junta Administradora Ad Hoc de PDVSA asegura que continuar\u00e1 utilizando todos los recursos jur\u00eddicos disponibles en su compromiso con la justicia, la transparencia y el cumplimiento de las leyes, actuando en beneficio de los intereses de la compa\u00f1\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>CITGO contin\u00faa operando con resultados positivos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo trimestre de este a\u00f1o CITGO Petroleum Corporation realiz\u00f3 un programa de mantenimiento mayor y modernizaci\u00f3n en todo su sistema de refinaci\u00f3n. Estos planes postergados, por las negligentes gestiones de Hugo Ch\u00e1vez y Nicol\u00e1s Maduro, provocaron da\u00f1os significativos en las instalaciones, disminuci\u00f3n en la eficiencia operativa, incremento de los riesgos de accidentes y da\u00f1os al medio ambiente y p\u00e9rdida de valor de los activos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La realizaci\u00f3n de estos trabajos de mantenimiento requirieron paradas totales de plantas por varias semanas. En cuanto a la capacidad promedio de procesamiento de crudo y otras corrientes de refinaci\u00f3n, entre principios de enero y finales de septiembre de 2023, se alcanz\u00f3 la cifra de 787,000 b\/d, lo que representa una disminuci\u00f3n de 20,000 b\/d con respecto al mismo periodo de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, gracias a la inversi\u00f3n estrat\u00e9gica e inteligente, en el mantenimiento correctivo y preventivo de sus tres refiner\u00edas (Lake Charles, Corpus Christi y Lemont), los resultados de la empresa en el tercer trimestre fueron muy positivos. Se alcanz\u00f3 una capacidad de procesamiento de crudo de 774,000 b\/d lo que equivale a una eficiencia operativa de aproximadamente 96% con respecto a su capacidad nominal de 807,000 b\/d. Durante ese trimestre, tambi\u00e9n se procesaron 37,000 b\/d de otras corrientes de refiner\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En octubre, se produjo un incremento significativo en el volumen total de crudo y otras corrientes procesadas. La capacidad de crudo alcanz\u00f3 769,000 b\/d, mientras que la de otras alimentaciones fue de 125,000 b\/d, resultando en un volumen total procesado de 894,000 b\/d.<br> <br>No obstante, los ingresos se vieron afectados durante el segundo y tercer trimestre debido a factores ex\u00f3genos que impactaron los precios del crudo y los mercados de combustibles en diversas regiones geogr\u00e1ficas, especialmente en los estados de la costa del Golfo de M\u00e9xico y del Medio Oeste de los Estados Unidos. Los m\u00e1rgenes de refinaci\u00f3n disminuyeron aproximadamente un 40% durante el segundo y tercer trimestre en comparaci\u00f3n con el primer trimestre de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al cierre de este 2024, podemos afirmar de forma categ\u00f3rica que CITGO sigue siendo un activo estrat\u00e9gico propiedad de PDVSA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">30 de Diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: PDVSA Ad Hoc<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EnergiesNet.com 21 01 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/\"> <span class=\"screen-reader-text\">PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":24624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[45],"tags":[],"class_list":["post-24623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-diarias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EnergiesNet\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet\" \/>\n\t\t<meta property=\"og:description\" content=\"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-21T15:27:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-21T15:36:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/\/EnergiesNet\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@EnergiesNet1\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/energiesnet.com\/espanol\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#blogposting\",\"name\":\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet\",\"headline\":\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones\",\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pdvsa_ad-hoc.jpg\",\"width\":600,\"height\":367},\"datePublished\":\"2025-01-21T11:27:06-04:00\",\"dateModified\":\"2025-01-21T11:36:00-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#webpage\"},\"articleSection\":\"Noticias Diarias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/#listItem\",\"name\":\"Noticias Diarias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/#listItem\",\"position\":2,\"name\":\"Noticias Diarias\",\"item\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#listItem\",\"name\":\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#listItem\",\"position\":3,\"name\":\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/category\\\/noticias-diarias\\\/#listItem\",\"name\":\"Noticias Diarias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"telephone\":\"+584142763041\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/EnergiesNet-Logo-200.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#organizationLogo\",\"width\":200,\"height\":220},\"image\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/\\\/EnergiesNet\",\"https:\\\/\\\/twitter.com\\\/EnergiesNet1\",\"https:\\\/\\\/www.instagram.com\\\/energiesnet\\\/\",\"https:\\\/\\\/linkedin.com\\\/in\\\/elio-ohep-a465b78\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/\",\"name\":\"EnergiesNet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"EnergiesNet\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#webpage\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/\",\"name\":\"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet\",\"description\":\"Gesti\\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/author\\\/elioohep\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pdvsa_ad-hoc.jpg\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#mainImage\",\"width\":600,\"height\":367},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\\\/#mainImage\"},\"datePublished\":\"2025-01-21T11:27:06-04:00\",\"dateModified\":\"2025-01-21T11:36:00-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#website\",\"url\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/\",\"name\":\"EnergiestNet\",\"description\":\"Latin America Energy, Oil ,  Gas & Renewals\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/energiesnet.com\\\/espanol\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet","description":"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los","canonical_url":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#blogposting","name":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet","headline":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones","author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2025\/01\/pdvsa_ad-hoc.jpg","width":600,"height":367},"datePublished":"2025-01-21T11:27:06-04:00","dateModified":"2025-01-21T11:36:00-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#webpage"},"isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#webpage"},"articleSection":"Noticias Diarias"},{"@type":"BreadcrumbList","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","position":1,"name":"Inicio","item":"https:\/\/energiesnet.com\/espanol","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/#listItem","name":"Noticias Diarias"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/#listItem","position":2,"name":"Noticias Diarias","item":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#listItem","name":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#listItem","position":3,"name":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones","previousItem":{"@type":"ListItem","@id":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/#listItem","name":"Noticias Diarias"}}]},{"@type":"Organization","@id":"https:\/\/energiesnet.com\/espanol\/#organization","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","url":"https:\/\/energiesnet.com\/espanol\/","telephone":"+584142763041","logo":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2022\/12\/EnergiesNet-Logo-200.jpg","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#organizationLogo","width":200,"height":220},"image":{"@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/\/EnergiesNet","https:\/\/twitter.com\/EnergiesNet1","https:\/\/www.instagram.com\/energiesnet\/","https:\/\/linkedin.com\/in\/elio-ohep-a465b78"]},{"@type":"Person","@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author","url":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/","name":"EnergiesNet","image":{"@type":"ImageObject","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5412deb1089370e2bdf1d1310563df78bf3dc9f9e388ca5748bced95cfdb664b?s=96&d=mm&r=g","width":96,"height":96,"caption":"EnergiesNet"}},{"@type":"WebPage","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#webpage","url":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/","name":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet","description":"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/energiesnet.com\/espanol\/#website"},"breadcrumb":{"@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#breadcrumblist"},"author":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"creator":{"@id":"https:\/\/energiesnet.com\/espanol\/author\/elioohep\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/energiesnet.com\/espanol\/wp-content\/uploads\/2025\/01\/pdvsa_ad-hoc.jpg","@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#mainImage","width":600,"height":367},"primaryImageOfPage":{"@id":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/#mainImage"},"datePublished":"2025-01-21T11:27:06-04:00","dateModified":"2025-01-21T11:36:00-04:00"},{"@type":"WebSite","@id":"https:\/\/energiesnet.com\/espanol\/#website","url":"https:\/\/energiesnet.com\/espanol\/","name":"EnergiestNet","description":"Latin America Energy, Oil ,  Gas & Renewals","inLanguage":"es-ES","publisher":{"@id":"https:\/\/energiesnet.com\/espanol\/#organization"}}]},"og:locale":"es_ES","og:site_name":"EnergiestNet - Latin America Energy, Oil ,  Gas &amp; Renewals","og:type":"article","og:title":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet","og:description":"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los","og:url":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/","og:image":"https:\/\/energiesnet.com\/espanol","og:image:secure_url":"https:\/\/energiesnet.com\/espanol","article:published_time":"2025-01-21T15:27:06+00:00","article:modified_time":"2025-01-21T15:36:00+00:00","article:publisher":"https:\/\/www.facebook.com\/\/EnergiesNet","twitter:card":"summary_large_image","twitter:site":"@EnergiesNet1","twitter:title":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones - EnergiestNet","twitter:description":"Gesti\u00f3n de PDVSA Ad Hoc y CITGO durante 2024 EnergiesNet CARACAS EnergiesNet.com 21 01 2025 La Junta Administradora Ad Hoc de PDVSA reitera su compromiso con la defensa de los activos de Venezuela en el exterior, cumpliendo con su mandato de salvaguardar los activos de PDVSA. Durante 2024, se han enfrentado demandas que superan los","twitter:creator":"@EnergiesNet1","twitter:image":"https:\/\/energiesnet.com\/espanol"},"aioseo_meta_data":{"post_id":"24623","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-21 15:27:08","updated":"2025-06-04 17:37:49","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/\" title=\"Noticias Diarias\">Noticias Diarias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/energiesnet.com\/espanol"},{"label":"Noticias Diarias","link":"https:\/\/energiesnet.com\/espanol\/category\/noticias-diarias\/"},{"label":"PDVSA Reafirma Defensa de Activos Venezolanos ante Reclamos de $20 Mil Millones","link":"https:\/\/energiesnet.com\/espanol\/pdvsa-reafirma-defensa-de-activos-venezolanos-ante-reclamos-de-20-mil-millones\/"}],"_links":{"self":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/24623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/comments?post=24623"}],"version-history":[{"count":0,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/posts\/24623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media\/24624"}],"wp:attachment":[{"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/media?parent=24623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/categories?post=24623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energiesnet.com\/espanol\/wp-json\/wp\/v2\/tags?post=24623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}